{"id":2933,"date":"2020-09-10T05:37:32","date_gmt":"2020-09-10T10:07:32","guid":{"rendered":"https:\/\/carlossandoval.wpengine.com\/?page_id=2933"},"modified":"2021-01-20T04:23:48","modified_gmt":"2021-01-20T08:53:48","slug":"hay-alguien-determinado-inelegible-para-una-visa-de-prometido","status":"publish","type":"page","link":"https:\/\/www.carlosesandoval.com\/es\/hay-alguien-determinado-inelegible-para-una-visa-de-prometido\/","title":{"rendered":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido?"},"content":{"rendered":"[vc_row][vc_column][vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que no han hecho nada que los haga inelegibles para solicitar una tarjeta verde. Algunas de estas razones pueden ser criminales, fraude o si han intentado obtener beneficios de inmigraci\u00f3n ilegalmente en el pasado. Adem\u00e1s, deber\u00e1n demostrar que es un matrimonio real. Una de las principales cosas que el consulado evaluar\u00e1 durante el momento de emitir una decisi\u00f3n en el caso es asegurarse de que sea una relaci\u00f3n real y que en realidad tengan la intenci\u00f3n de casarse una vez que el prometido ingrese a los Estados Unidos.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfPuedo llevar a los hijos de mi prometido a los Estados Unidos tambi\u00e9n?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]S\u00ed, los hijos de un prometido tambi\u00e9n pueden incluirse en la petici\u00f3n. El prometido ingresar\u00e1 con una visa K-1 y los ni\u00f1os ingresar\u00e1n con una visa K-2 y tambi\u00e9n podr\u00e1n solicitar el ajuste de estado cuando ingresen a los Estados Unidos, siempre que sean menores de 21 a\u00f1os.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfQu\u00e9 puedo hacer si mi solicitud de visa K-1 fue denegada?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Si su solicitud para la visa K-1 es denegada, puede solicitar revisar el motivo de la denegaci\u00f3n para ver si hay algo que pueda superarse. Por ejemplo, tal vez usted no envi\u00f3 suficiente evidencia de la relaci\u00f3n y tal vez la petici\u00f3n puede ser presentada nuevamente. Si la persona es inadmisible debido a un delito o fraude o alguna otra causa de inadmisibilidad, tambi\u00e9n hay algunas exenciones que se pueden presentar para permitir que la persona obtenga su visa de prometido.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfQui\u00e9n es elegible para solicitar y eliminar las condiciones de residencia permanente basada en el matrimonio?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Cuando una persona ingresa a los Estados Unidos con una visa de prometido y se casa, el siguiente paso ser\u00e1 solicitar el ajuste de estado. La tarjeta de residencia inicial ser\u00e1 condicional y luego dos a\u00f1os m\u00e1s tarde deber\u00e1n presentar una solicitud para eliminar las condiciones de su residencia porque esa tarjeta verde inicial es condicional. Lo que la pareja tiene que hacer es asegurarse de que tengan suficiente evidencia que demuestre que es un matrimonio real para el final de los dos a\u00f1os poder presentar toda esa documentaci\u00f3n con la solicitud para eliminar las condiciones en su residencia.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfQu\u00e9 sucede si llego tarde a solicitar la eliminaci\u00f3n de las condiciones en la residencia?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Si se retrasa en la solicitud para eliminar las condiciones en la residencia, a veces es posible que se aplique una excepci\u00f3n a ese requisito si la persona puede demostrar que no se present\u00f3 la solicitud para eliminar las condiciones de la tarjeta verde por una buena raz\u00f3n. A veces se debe a que alguien ha tenido problemas de salud o simplemente puede tener problemas financieros. Siempre que una persona pueda demostrar que hubo una buena raz\u00f3n detr\u00e1s de la falta de solicitud a tiempo, entonces podemos solicitar una excepci\u00f3n a esa regla.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfQu\u00e9 generalmente detiene el proceso de aprobaci\u00f3n para una visa de prometido?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Lo m\u00e1s importante para este tipo de casos es hacerlo bien la primera vez. Cuando las personas han estado esperando durante mucho tiempo para que el caso sea aprobado, es porque a veces no lo hicieron bien para empezar. Algunas veces faltan documentos o a veces no tienen la evidencia correcta. Es muy importante asegurarse de que toda la documentaci\u00f3n sea correcta y de que todos los formularios se hayan preparado correctamente, que es lo que realmente tendr\u00e1 un impacto en la cantidad de tiempo que un caso como este puede tomar.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">\u00bfC\u00f3mo puede un abogado ayudar a alguien a obtener la visa de prometido y evitar las trampas relacionadas?<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Un abogado puede ayudar a alguien a obtener la visa de prometido y evitar las trampas relacionadas al analizar el caso desde el principio para asegurarse de que cumple con todos los requisitos. Por ejemplo, uno de los requisitos es que el extranjero y el solicitante deben haberse visto al menos una vez en los \u00faltimos dos a\u00f1os. Si alguien solicita este tipo de visa y no cumple con ese requisito, van a perder su dinero porque la petici\u00f3n no ser\u00e1 aprobada. Van a estar perdiendo el tiempo porque el gobierno les enviar\u00e1 una negativa diciendo que no cumplen con todos los requisitos. Una de las primeras cosas que un abogado puede hacer es asegurarse de que una persona cumpla con todos los requisitos. Si no cumplen con este, entonces un viaje r\u00e1pido para ver a su prometido se encargar\u00e1 de eso.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Una vez que nos hemos asegurado de que se cumplan todos los requisitos, nos aseguramos de que la aplicaci\u00f3n se prepare correctamente con todos los documentos para evitar una solicitud de pruebas. Una solicitud de evidencia es cuando el gobierno env\u00eda un documento que indica que necesitan documentaci\u00f3n adicional y retrasa el proceso. A veces, este proceso puede llevar de tres a cuatro meses o incluso hasta 12 meses porque no enviaron toda la informaci\u00f3n que se requer\u00eda. Adem\u00e1s, con respecto a la evidencia que quieren llevar a la entrevista, si tienen pruebas de que existe un matrimonio real, es m\u00e1s probable que el caso se apruebe de manera m\u00e1s oportuna en lugar de ir a la entrevista y no tener toda esa documentaci\u00f3n. Solo hacerlo correctamente al principio es muy importante para garantizar que el caso sea exitoso.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:15px\"><\/div><h1 class=\"vcex-module vcex-heading vcex-heading-plain\" style=\"color:#000000;font-size:1.7142857142857142rem;font-weight:600;\"><span class=\"vcex-heading-inner clr\">Informaci\u00f3n adicional sobre visas K-1 o de novios en los Estados Unidos<\/span><\/h1><div class=\"vcex-spacing\" style=\"height:20px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Una de las cosas m\u00e1s importantes cuando trabajas en un caso como este es obtener representaci\u00f3n legal adecuada para asegurarte de que toda la documentaci\u00f3n se realiza correctamente y para garantizar que se cumplan todos los requisitos y se eviten los retrasos innecesarios.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:10px\"><\/div>[\/vc_column][\/vc_row][vc_row css=\u00bb.vc_custom_1599288021446{margin-top: 10px !important;background-color: #f7f7f7 !important;}\u00bb][vc_column]<div class=\"vcex-spacing\" style=\"height:25px\"><\/div>[vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]Para obtener m\u00e1s informaci\u00f3n sobre Inelegibilidad para Visas de prometido, una consulta inicial gratuita es su pr\u00f3ximo mejor paso. Obtenga la informaci\u00f3n y las respuestas legales que est\u00e1 buscando llamando al <a href=\"http:\/\/Tel:+19543066921\">(954) 306-6921<\/a> hoy.[\/vc_column_text]<div class=\"vcex-spacing\" style=\"height:25px\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"vcex-spacing\" style=\"height:50px\"><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text color=\u00bb#222222&#8243; font_size=\u00bb16px\u00bb]S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-2933","page","type-page","status-publish","hentry","entry","no-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida\" \/>\n<meta property=\"og:description\" content=\"S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que no han hecho nada que los haga inelegibles para solicitar una tarjeta verde. Algunas de estas razones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/\" \/>\n<meta property=\"og:site_name\" content=\"Carlos Sandoval\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/abogadocarlosesandoval\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-20T08:53:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida\" \/>\n<meta name=\"twitter:description\" content=\"S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que no han hecho nada que los haga inelegibles para solicitar una tarjeta verde. Algunas de estas razones\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/is-anyone-determined-ineligible-for-a-fiance-visa\\\/\",\"url\":\"https:\\\/\\\/www.carlosesandoval.com\\\/is-anyone-determined-ineligible-for-a-fiance-visa\\\/\",\"name\":\"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#website\"},\"datePublished\":\"2020-09-10T10:07:32+00:00\",\"dateModified\":\"2021-01-20T08:53:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/is-anyone-determined-ineligible-for-a-fiance-visa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.carlosesandoval.com\\\/is-anyone-determined-ineligible-for-a-fiance-visa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/is-anyone-determined-ineligible-for-a-fiance-visa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.carlosesandoval.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#website\",\"url\":\"https:\\\/\\\/www.carlosesandoval.com\\\/\",\"name\":\"Carlos Sandoval, P.A.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.carlosesandoval.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#organization\",\"name\":\"Carlos E. Sandoval, P.A.\",\"url\":\"https:\\\/\\\/www.carlosesandoval.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.carlosesandoval.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-2x-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.carlosesandoval.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-2x-retina.png\",\"width\":848,\"height\":134,\"caption\":\"Carlos E. Sandoval, P.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.carlosesandoval.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/abogadocarlosesandoval\",\"https:\\\/\\\/www.instagram.com\\\/carlosesandovalpa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/carlosesandoval\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CarlosesandovalPA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida","og_description":"S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que no han hecho nada que los haga inelegibles para solicitar una tarjeta verde. Algunas de estas razones","og_url":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/","og_site_name":"Carlos Sandoval","article_publisher":"https:\/\/www.facebook.com\/abogadocarlosesandoval","article_modified_time":"2021-01-20T08:53:48+00:00","twitter_card":"summary_large_image","twitter_title":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida","twitter_description":"S\u00ed, alguien puede ser considerado inelegible para una visa de prometido. Una de las cosas que una persona tiene que mostrar para poder obtener la visa de prometido es que esa persona no es inadmisible. Inadmisible significa que no han hecho nada que los haga inelegibles para solicitar una tarjeta verde. Algunas de estas razones","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/","url":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/","name":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido? | Bilingual Immigration Attorney in South Florida - Bilingual Immigration Attorney in South Florida","isPartOf":{"@id":"https:\/\/www.carlosesandoval.com\/#website"},"datePublished":"2020-09-10T10:07:32+00:00","dateModified":"2021-01-20T08:53:48+00:00","breadcrumb":{"@id":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.carlosesandoval.com\/is-anyone-determined-ineligible-for-a-fiance-visa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.carlosesandoval.com\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfHay Alguien Determinado Inelegible Para Una Visa De Prometido?"}]},{"@type":"WebSite","@id":"https:\/\/www.carlosesandoval.com\/#website","url":"https:\/\/www.carlosesandoval.com\/","name":"Carlos Sandoval, P.A.","description":"","publisher":{"@id":"https:\/\/www.carlosesandoval.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.carlosesandoval.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.carlosesandoval.com\/#organization","name":"Carlos E. Sandoval, P.A.","url":"https:\/\/www.carlosesandoval.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.carlosesandoval.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.carlosesandoval.com\/wp-content\/uploads\/2022\/05\/logo-2x-retina.png","contentUrl":"https:\/\/www.carlosesandoval.com\/wp-content\/uploads\/2022\/05\/logo-2x-retina.png","width":848,"height":134,"caption":"Carlos E. Sandoval, P.A."},"image":{"@id":"https:\/\/www.carlosesandoval.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/abogadocarlosesandoval","https:\/\/www.instagram.com\/carlosesandovalpa\/","https:\/\/www.linkedin.com\/in\/carlosesandoval\/","https:\/\/www.youtube.com\/@CarlosesandovalPA"]}]}},"_links":{"self":[{"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/pages\/2933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/comments?post=2933"}],"version-history":[{"count":0,"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/pages\/2933\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carlosesandoval.com\/es\/wp-json\/wp\/v2\/media?parent=2933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}